{"id":14,"date":"2025-02-17T08:43:55","date_gmt":"2025-02-17T08:43:55","guid":{"rendered":"https:\/\/adremlimburg.nextlead.nl\/?page_id=14"},"modified":"2025-12-01T12:32:39","modified_gmt":"2025-12-01T10:32:39","slug":"mijn-account","status":"publish","type":"page","link":"https:\/\/adremlimburg.nextlead.nl\/en\/mijn-account\/","title":{"rendered":"Mijn account"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"14\" class=\"elementor elementor-14\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b15f253 e-flex e-con-boxed e-con e-parent\" data-id=\"2b15f253\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca12f74 e-my-account-tabs-horizontal elementor-widget elementor-widget-woocommerce-my-account\" data-id=\"ca12f74\" data-element_type=\"widget\" data-widget_type=\"woocommerce-my-account.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-my-account-tab e-my-account-tab__\">\t\t\t<div class=\"woocommerce\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Dashboard Bestellingen Adressen Accountgegevens Uitloggen Dashboard Bestellingen Adressen Accountgegevens Uitloggen Dashboard Bestellingen Adressen Accountgegevens Uitloggen Dashboard Bestellingen Adressen Accountgegevens Uitloggen Hallo Max (niet Max? Log uit) Vanaf je account dashboard kun je je recente bestellingen bekijken, je verzend- en factuuradressen beheren en je wachtwoord en account details bewerken.<\/p>","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-14","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/adremlimburg.nextlead.nl\/en\/wp-json\/wp\/v2\/pages\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adremlimburg.nextlead.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/adremlimburg.nextlead.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/adremlimburg.nextlead.nl\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/adremlimburg.nextlead.nl\/en\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":0,"href":"https:\/\/adremlimburg.nextlead.nl\/en\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"wp:attachment":[{"href":"https:\/\/adremlimburg.nextlead.nl\/en\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}